{"id":620,"date":"2016-11-08T13:46:11","date_gmt":"2016-11-08T13:46:11","guid":{"rendered":"http:\/\/dietetforme.fr\/?p=620"},"modified":"2019-02-19T13:31:50","modified_gmt":"2019-02-19T13:31:50","slug":"les-haricots-aliment-magique","status":"publish","type":"post","link":"https:\/\/dietetforme.fr\/blog\/les-haricots-aliment-magique\/","title":{"rendered":"Les Haricots , aliment magique ?"},"content":{"rendered":"<p><strong>Les haricots ( appart les haricots verts)\u00a0font partie des l\u00e9gumineuses,<\/strong> ce sont des aliments tr\u00e8s riches en fibres et en prot\u00e9ines v\u00e9g\u00e9tales qui peuvent stimuler une perte de poids. En effet les l\u00e9gumineuses contribuent \u00e0 stimuler la combustion des calories, des graisses, \u00e0 freiner la faim et perdre de la masse graisseuse au niveau du ventre.<\/p>\n<p><strong>Ces l\u00e9gumineuses sont sans gluten, riche en vitamines, min\u00e9raux et en antioxydant.\u00a0<\/strong><\/p>\n<p>Augmenter la portion de l\u00e9gumineuse ( lentilles, haricots rouges, haricots blanc, f\u00e8ves, flageolets, pois cass\u00e9s, pois chiches&#8230;) est un moyen efficace et simple de <strong>vous aidez \u00e0 perdre du poids de mani\u00e8res durables.\u00a0<\/strong><\/p>\n<p>Voici 5 mani\u00e8res d&rsquo;incorporer les haricots d&rsquo;une mani\u00e8re d\u00e9licieuse et facile :<\/p>\n<ul>\n<li><em><strong>Des haricots plut\u00f4t que la viande :\u00a0<\/strong><\/em><\/li>\n<\/ul>\n<p>Les haricots sont d&rsquo;abord beaucoup moins chers, mais utiliser des haricots \u00e0 la place de la viande est un gain de temps important. Les haricots noirs, pinto ou blanc peuvent \u00eatre cuits, mis en salade ou dans des tacos, incorporez dans les lasagnes, les hamburgers ou poivrons farcies, entiers ou \u00e9cras\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<p>Associ\u00e9 avec des c\u00e9r\u00e9ales, cette association vous permettra d&rsquo;avoir un bon apport de prot\u00e9ine.<\/p>\n<ul>\n<li><em><strong>Des haricots plut\u00f4t que de l&rsquo;amidon\u00a0<\/strong><\/em><\/li>\n<\/ul>\n<p>Comme les haricots fournissent \u00e0 la fois des prot\u00e9ines et des glucides riches en fibres, ils servent \u00e0 double usage\u00a0: vous pouvez les utiliser \u00e0 la place des prot\u00e9ines animales, ou en remplacement des amidons traditionnels, comme le riz, le ma\u00efs ou les pommes de terre.<\/p>\n<p>Ils fonctionnent bien comme un plat d\u2019accompagnement ou incorpor\u00e9 dans des recettes. Par exemple, dans les soupes, utilisez des haricots au lieu des p\u00e2tes ou des nouilles, ou ajoutez-les \u00e0 une salade au lieu du quinoa.<\/p>\n<ul>\n<li><em><strong>Des haricots plut\u00f4t que des produits laitiers :\u00a0<\/strong><\/em><\/li>\n<\/ul>\n<p>Les haricots entiers ou les farines de haricots, comme la f\u00e8ve, la farine de haricot noir ou blanc, peuvent constituer des bases ou des \u00e9paississants id\u00e9aux pour les sauces et les soupes cr\u00e9meuses, vous pouvez donc remplacer le lait, la cr\u00e8me ou le beurre par ces l\u00e9gumineuses.<\/p>\n<p>C&rsquo;est une tr\u00e8s bonne alternative pour les personnes intol\u00e9rants au lactose .<\/p>\n<ul>\n<li><strong><em>Des haricots en collation :\u00a0<\/em><\/strong><\/li>\n<\/ul>\n<p>De nombreuses p\u00e2tes \u00e0 tartiner peuvent \u00eates fait \u00e0 base de p\u00e2te de l\u00e9gumineuse comme le Houmous que l&rsquo;on peut tartiner sur du pain aux c\u00e9r\u00e9ales ou complet. Cette collation est seine pleine de nutriment, et remplacera simplement des produits industriels.<\/p>\n<ul>\n<li><em><strong>Des haricots en dessert :<\/strong><\/em><\/li>\n<\/ul>\n<p>Un brownie de haricots, une cr\u00e8me glac\u00e9e de haricot ? et oui ces desserts existent et son d\u00e9licieux. Il y a de nombreuses mani\u00e8res d&rsquo;incorporer les haricots dans des mets sucr\u00e9s. Vous pouvez les utilisez dans les poudings, les smoothies, les cr\u00e8mes glac\u00e9es, leur go\u00fbt est neutre mais ils ajoutent de la texture et \u00e9paississent vos desserts.<\/p>\n<p>La farine d&rsquo;haricot remplace la farine de bl\u00e9 classique, vous obtiendrez la m\u00eame texture, et vos pr\u00e9parations seront sans gluten et vous augmentez vos fibres !<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les haricots ( appart les haricots verts)\u00a0font partie des l\u00e9gumineuses, ce sont des aliments tr\u00e8s riches en fibres et en prot\u00e9ines v\u00e9g\u00e9tales qui peuvent stimuler une perte de poids. En effet les l\u00e9gumineuses contribuent \u00e0 stimuler la combustion des calories, des graisses, \u00e0 freiner la faim et perdre de la masse graisseuse au niveau du ventre. Ces l\u00e9gumineuses sont sans gluten, riche en vitamines, min\u00e9raux et en antioxydant.\u00a0 Augmenter la portion de l\u00e9gumineuse ( lentilles, haricots rouges, haricots blanc, f\u00e8ves, flageolets, pois cass\u00e9s, pois chiches&#8230;) est un moyen efficace et simple de vous aidez \u00e0 perdre du poids de mani\u00e8res durables.\u00a0 Voici 5 mani\u00e8res d&rsquo;incorporer les haricots d&rsquo;une mani\u00e8re d\u00e9licieuse et facile : Des haricots plut\u00f4t que la viande :\u00a0 Les haricots sont d&rsquo;abord beaucoup moins chers, mais utiliser des haricots \u00e0 la place de la viande est un gain de temps important. Les haricots noirs, pinto ou blanc peuvent \u00eatre cuits, mis en salade ou dans des tacos, incorporez dans les lasagnes, les hamburgers ou poivrons farcies, entiers ou \u00e9cras\u00e9s. &nbsp; Associ\u00e9 avec des c\u00e9r\u00e9ales, cette association vous permettra d&rsquo;avoir un bon apport de prot\u00e9ine. Des haricots plut\u00f4t que de l&rsquo;amidon\u00a0 Comme les haricots fournissent \u00e0 la fois des prot\u00e9ines et des glucides riches en fibres, ils servent \u00e0 double usage\u00a0: vous pouvez les utiliser \u00e0 la place des prot\u00e9ines animales, ou en remplacement des amidons traditionnels, comme le riz, le ma\u00efs ou les pommes de terre. Ils fonctionnent bien comme un plat d\u2019accompagnement ou incorpor\u00e9 dans des recettes. Par exemple, dans les soupes, utilisez des haricots au lieu des p\u00e2tes ou des nouilles, ou ajoutez-les \u00e0 une salade au lieu du quinoa. Des haricots plut\u00f4t que des produits laitiers :\u00a0 Les haricots entiers ou les farines de haricots, comme la f\u00e8ve, la farine de haricot noir ou blanc, peuvent constituer des bases ou des \u00e9paississants id\u00e9aux pour les sauces et les soupes cr\u00e9meuses, vous pouvez donc remplacer le lait, la cr\u00e8me ou le beurre par ces l\u00e9gumineuses. C&rsquo;est une tr\u00e8s bonne alternative pour les personnes intol\u00e9rants au lactose . Des haricots en collation :\u00a0 De nombreuses p\u00e2tes \u00e0 tartiner peuvent \u00eates fait \u00e0 base de p\u00e2te de l\u00e9gumineuse comme le Houmous que l&rsquo;on peut tartiner sur du pain aux c\u00e9r\u00e9ales ou complet. Cette collation est seine pleine de nutriment, et remplacera simplement des produits industriels. Des haricots en dessert : Un brownie de haricots, une cr\u00e8me glac\u00e9e de haricot ? et oui ces desserts existent et son d\u00e9licieux. Il y a de nombreuses mani\u00e8res d&rsquo;incorporer les haricots dans des mets sucr\u00e9s. Vous pouvez les utilisez dans les poudings, les smoothies, les cr\u00e8mes glac\u00e9es, leur go\u00fbt est neutre mais ils ajoutent de la texture et \u00e9paississent vos desserts. La farine d&rsquo;haricot remplace la farine de bl\u00e9 classique, vous obtiendrez la m\u00eame texture, et vos pr\u00e9parations seront sans gluten et vous augmentez vos fibres ! &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":621,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"footnotes":""},"categories":[4,3],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les Haricots , aliment magique ? - Di\u00e8t et Forme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dietetforme.fr\/blog\/les-haricots-aliment-magique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Haricots , aliment magique ? - Di\u00e8t et Forme\" \/>\n<meta property=\"og:description\" content=\"Les haricots ( appart les haricots verts)\u00a0font partie des l\u00e9gumineuses, ce sont des aliments tr\u00e8s riches en fibres et en prot\u00e9ines v\u00e9g\u00e9tales qui peuvent stimuler une perte de poids. En effet les l\u00e9gumineuses contribuent \u00e0 stimuler la combustion des calories, des graisses, \u00e0 freiner la faim et perdre de la masse graisseuse au niveau du ventre. Ces l\u00e9gumineuses sont sans gluten, riche en vitamines, min\u00e9raux et en antioxydant.\u00a0 Augmenter la portion de l\u00e9gumineuse ( lentilles, haricots rouges, haricots blanc, f\u00e8ves, flageolets, pois cass\u00e9s, pois chiches&#8230;) est un moyen efficace et simple de vous aidez \u00e0 perdre du poids de mani\u00e8res durables.\u00a0 Voici 5 mani\u00e8res d&rsquo;incorporer les haricots d&rsquo;une mani\u00e8re d\u00e9licieuse et facile : Des haricots plut\u00f4t que la viande :\u00a0 Les haricots sont d&rsquo;abord beaucoup moins chers, mais utiliser des haricots \u00e0 la place de la viande est un gain de temps important. Les haricots noirs, pinto ou blanc peuvent \u00eatre cuits, mis en salade ou dans des tacos, incorporez dans les lasagnes, les hamburgers ou poivrons farcies, entiers ou \u00e9cras\u00e9s. &nbsp; Associ\u00e9 avec des c\u00e9r\u00e9ales, cette association vous permettra d&rsquo;avoir un bon apport de prot\u00e9ine. Des haricots plut\u00f4t que de l&rsquo;amidon\u00a0 Comme les haricots fournissent \u00e0 la fois des prot\u00e9ines et des glucides riches en fibres, ils servent \u00e0 double usage\u00a0: vous pouvez les utiliser \u00e0 la place des prot\u00e9ines animales, ou en remplacement des amidons traditionnels, comme le riz, le ma\u00efs ou les pommes de terre. Ils fonctionnent bien comme un plat d\u2019accompagnement ou incorpor\u00e9 dans des recettes. Par exemple, dans les soupes, utilisez des haricots au lieu des p\u00e2tes ou des nouilles, ou ajoutez-les \u00e0 une salade au lieu du quinoa. Des haricots plut\u00f4t que des produits laitiers :\u00a0 Les haricots entiers ou les farines de haricots, comme la f\u00e8ve, la farine de haricot noir ou blanc, peuvent constituer des bases ou des \u00e9paississants id\u00e9aux pour les sauces et les soupes cr\u00e9meuses, vous pouvez donc remplacer le lait, la cr\u00e8me ou le beurre par ces l\u00e9gumineuses. C&rsquo;est une tr\u00e8s bonne alternative pour les personnes intol\u00e9rants au lactose . Des haricots en collation :\u00a0 De nombreuses p\u00e2tes \u00e0 tartiner peuvent \u00eates fait \u00e0 base de p\u00e2te de l\u00e9gumineuse comme le Houmous que l&rsquo;on peut tartiner sur du pain aux c\u00e9r\u00e9ales ou complet. Cette collation est seine pleine de nutriment, et remplacera simplement des produits industriels. Des haricots en dessert : Un brownie de haricots, une cr\u00e8me glac\u00e9e de haricot ? et oui ces desserts existent et son d\u00e9licieux. Il y a de nombreuses mani\u00e8res d&rsquo;incorporer les haricots dans des mets sucr\u00e9s. Vous pouvez les utilisez dans les poudings, les smoothies, les cr\u00e8mes glac\u00e9es, leur go\u00fbt est neutre mais ils ajoutent de la texture et \u00e9paississent vos desserts. La farine d&rsquo;haricot remplace la farine de bl\u00e9 classique, vous obtiendrez la m\u00eame texture, et vos pr\u00e9parations seront sans gluten et vous augmentez vos fibres ! &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dietetforme.fr\/blog\/les-haricots-aliment-magique\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e8t et Forme\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lddietetforme\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-08T13:46:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-19T13:31:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dietetforme.fr\/blog\/wp-content\/uploads\/2016\/11\/beans-1001032_640-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"L\u00e9onore Duchez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"L\u00e9onore Duchez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/les-haricots-aliment-magique\/\",\"url\":\"https:\/\/dietetforme.fr\/blog\/les-haricots-aliment-magique\/\",\"name\":\"Les Haricots , aliment magique ? - Di\u00e8t et Forme\",\"isPartOf\":{\"@id\":\"https:\/\/dietetforme.fr\/blog\/#website\"},\"datePublished\":\"2016-11-08T13:46:11+00:00\",\"dateModified\":\"2019-02-19T13:31:50+00:00\",\"author\":{\"@id\":\"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/dfda5751b55409cd7b4557f58765f7a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/dietetforme.fr\/blog\/les-haricots-aliment-magique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dietetforme.fr\/blog\/les-haricots-aliment-magique\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/les-haricots-aliment-magique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dietetforme.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MES CONSEILS\",\"item\":\"https:\/\/dietetforme.fr\/blog\/cat\/trucs-astuces-conseils-nutrition-dietetiques\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les Haricots , aliment magique ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/#website\",\"url\":\"https:\/\/dietetforme.fr\/blog\/\",\"name\":\"Di\u00e8t et Forme\",\"description\":\"Blog de recettes et astuces di\u00e9t\u00e9tiques\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dietetforme.fr\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/dfda5751b55409cd7b4557f58765f7a2\",\"name\":\"L\u00e9onore Duchez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bcb12a51f6392d50f0d406d3f084b785?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bcb12a51f6392d50f0d406d3f084b785?s=96&d=mm&r=g\",\"caption\":\"L\u00e9onore Duchez\"},\"url\":\"https:\/\/dietetforme.fr\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Haricots , aliment magique ? - Di\u00e8t et Forme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dietetforme.fr\/blog\/les-haricots-aliment-magique\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Haricots , aliment magique ? - Di\u00e8t et Forme","og_description":"Les haricots ( appart les haricots verts)\u00a0font partie des l\u00e9gumineuses, ce sont des aliments tr\u00e8s riches en fibres et en prot\u00e9ines v\u00e9g\u00e9tales qui peuvent stimuler une perte de poids. En effet les l\u00e9gumineuses contribuent \u00e0 stimuler la combustion des calories, des graisses, \u00e0 freiner la faim et perdre de la masse graisseuse au niveau du ventre. Ces l\u00e9gumineuses sont sans gluten, riche en vitamines, min\u00e9raux et en antioxydant.\u00a0 Augmenter la portion de l\u00e9gumineuse ( lentilles, haricots rouges, haricots blanc, f\u00e8ves, flageolets, pois cass\u00e9s, pois chiches&#8230;) est un moyen efficace et simple de vous aidez \u00e0 perdre du poids de mani\u00e8res durables.\u00a0 Voici 5 mani\u00e8res d&rsquo;incorporer les haricots d&rsquo;une mani\u00e8re d\u00e9licieuse et facile : Des haricots plut\u00f4t que la viande :\u00a0 Les haricots sont d&rsquo;abord beaucoup moins chers, mais utiliser des haricots \u00e0 la place de la viande est un gain de temps important. Les haricots noirs, pinto ou blanc peuvent \u00eatre cuits, mis en salade ou dans des tacos, incorporez dans les lasagnes, les hamburgers ou poivrons farcies, entiers ou \u00e9cras\u00e9s. &nbsp; Associ\u00e9 avec des c\u00e9r\u00e9ales, cette association vous permettra d&rsquo;avoir un bon apport de prot\u00e9ine. Des haricots plut\u00f4t que de l&rsquo;amidon\u00a0 Comme les haricots fournissent \u00e0 la fois des prot\u00e9ines et des glucides riches en fibres, ils servent \u00e0 double usage\u00a0: vous pouvez les utiliser \u00e0 la place des prot\u00e9ines animales, ou en remplacement des amidons traditionnels, comme le riz, le ma\u00efs ou les pommes de terre. Ils fonctionnent bien comme un plat d\u2019accompagnement ou incorpor\u00e9 dans des recettes. Par exemple, dans les soupes, utilisez des haricots au lieu des p\u00e2tes ou des nouilles, ou ajoutez-les \u00e0 une salade au lieu du quinoa. Des haricots plut\u00f4t que des produits laitiers :\u00a0 Les haricots entiers ou les farines de haricots, comme la f\u00e8ve, la farine de haricot noir ou blanc, peuvent constituer des bases ou des \u00e9paississants id\u00e9aux pour les sauces et les soupes cr\u00e9meuses, vous pouvez donc remplacer le lait, la cr\u00e8me ou le beurre par ces l\u00e9gumineuses. C&rsquo;est une tr\u00e8s bonne alternative pour les personnes intol\u00e9rants au lactose . Des haricots en collation :\u00a0 De nombreuses p\u00e2tes \u00e0 tartiner peuvent \u00eates fait \u00e0 base de p\u00e2te de l\u00e9gumineuse comme le Houmous que l&rsquo;on peut tartiner sur du pain aux c\u00e9r\u00e9ales ou complet. Cette collation est seine pleine de nutriment, et remplacera simplement des produits industriels. Des haricots en dessert : Un brownie de haricots, une cr\u00e8me glac\u00e9e de haricot ? et oui ces desserts existent et son d\u00e9licieux. Il y a de nombreuses mani\u00e8res d&rsquo;incorporer les haricots dans des mets sucr\u00e9s. Vous pouvez les utilisez dans les poudings, les smoothies, les cr\u00e8mes glac\u00e9es, leur go\u00fbt est neutre mais ils ajoutent de la texture et \u00e9paississent vos desserts. La farine d&rsquo;haricot remplace la farine de bl\u00e9 classique, vous obtiendrez la m\u00eame texture, et vos pr\u00e9parations seront sans gluten et vous augmentez vos fibres ! &nbsp;","og_url":"https:\/\/dietetforme.fr\/blog\/les-haricots-aliment-magique\/","og_site_name":"Di\u00e8t et Forme","article_publisher":"https:\/\/www.facebook.com\/lddietetforme\/","article_published_time":"2016-11-08T13:46:11+00:00","article_modified_time":"2019-02-19T13:31:50+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/dietetforme.fr\/blog\/wp-content\/uploads\/2016\/11\/beans-1001032_640-2.jpg","type":"image\/jpeg"}],"author":"L\u00e9onore Duchez","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"L\u00e9onore Duchez","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dietetforme.fr\/blog\/les-haricots-aliment-magique\/","url":"https:\/\/dietetforme.fr\/blog\/les-haricots-aliment-magique\/","name":"Les Haricots , aliment magique ? - Di\u00e8t et Forme","isPartOf":{"@id":"https:\/\/dietetforme.fr\/blog\/#website"},"datePublished":"2016-11-08T13:46:11+00:00","dateModified":"2019-02-19T13:31:50+00:00","author":{"@id":"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/dfda5751b55409cd7b4557f58765f7a2"},"breadcrumb":{"@id":"https:\/\/dietetforme.fr\/blog\/les-haricots-aliment-magique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dietetforme.fr\/blog\/les-haricots-aliment-magique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dietetforme.fr\/blog\/les-haricots-aliment-magique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dietetforme.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"MES CONSEILS","item":"https:\/\/dietetforme.fr\/blog\/cat\/trucs-astuces-conseils-nutrition-dietetiques\/"},{"@type":"ListItem","position":3,"name":"Les Haricots , aliment magique ?"}]},{"@type":"WebSite","@id":"https:\/\/dietetforme.fr\/blog\/#website","url":"https:\/\/dietetforme.fr\/blog\/","name":"Di\u00e8t et Forme","description":"Blog de recettes et astuces di\u00e9t\u00e9tiques","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dietetforme.fr\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/dfda5751b55409cd7b4557f58765f7a2","name":"L\u00e9onore Duchez","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bcb12a51f6392d50f0d406d3f084b785?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bcb12a51f6392d50f0d406d3f084b785?s=96&d=mm&r=g","caption":"L\u00e9onore Duchez"},"url":"https:\/\/dietetforme.fr\/blog\/author\/admin\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/posts\/620"}],"collection":[{"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/comments?post=620"}],"version-history":[{"count":1,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/posts\/620\/revisions"}],"predecessor-version":[{"id":622,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/posts\/620\/revisions\/622"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/media\/621"}],"wp:attachment":[{"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/media?parent=620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/categories?post=620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/tags?post=620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}