{"id":557,"date":"2016-09-02T09:16:53","date_gmt":"2016-09-02T09:16:53","guid":{"rendered":"http:\/\/dietetforme.fr\/?p=557"},"modified":"2019-02-19T13:32:18","modified_gmt":"2019-02-19T13:32:18","slug":"les-aliments-a-consommer-bio","status":"publish","type":"post","link":"https:\/\/dietetforme.fr\/blog\/les-aliments-a-consommer-bio\/","title":{"rendered":"Les aliments \u00e0 consommer Bio"},"content":{"rendered":"<p>Je reviens aujourd\u2019hui avec un nouvel article sur le Bio.<strong> Les produits biologiques ont fait une entr\u00e9e fracassante dans nos rayons depuis un moment maintenant, et vous \u00eates de plus en plus nombreux et nombreuses \u00e0 les consommer .<\/strong><\/p>\n<p>Personnellement je ne suis pas une militante du bio, cependant je privil\u00e9gie le bio sur certains aliments.<\/p>\n<p>Les aliments biologiques divisent les opinions, <span style=\"text-decoration: underline;\">souvent plus chers sont ils vraiment d\u00e9pourvus de pesticides ?<\/span> Je pense que oui en tout cas en partie, mais il faut savoir que si nous faisons <em>une comparaison nutritionnelle l&rsquo;alimentation biologique et \u00a0\u00bb classiques\u00a0\u00bb la diff\u00e9rence n&rsquo;est pas tr\u00e8s significative en moyenne . \u00a0<\/em><\/p>\n<p>Certains aliments, cependant quand ils sont cultiv\u00e9s de mani\u00e8re conventionnelle, exige un niveaux de pesticide assez important :<\/p>\n<ul>\n<li>Pommes<\/li>\n<li>Poivrons<\/li>\n<li>C\u00e9leri<\/li>\n<li>Cerises<\/li>\n<li>Raisins<\/li>\n<li>Chou fris\u00e9<\/li>\n<li>\u00c9pinard<\/li>\n<li>Nectarines<\/li>\n<li>P\u00eaches<\/li>\n<li>Fraises<\/li>\n<li>Concombres<\/li>\n<li>Tomates cerise<\/li>\n<li>Pois gourmand<\/li>\n<li>Pommes de terre<\/li>\n<\/ul>\n<p>Si vous voulez faire attention \u00e0 la quantit\u00e9 de pesticide ces aliments sont \u00e0 acheter de pr\u00e9f\u00e9rence bio, ainsi que le lait et les oeufs qui viennent directement des animaux .<\/p>\n<p>Si vous voulez faire quelques \u00e9conomie certains aliments ne sont cultiv\u00e9 qu&rsquo;avec tr\u00e8s peu de pesticides :<\/p>\n<ul>\n<li>Asperges<\/li>\n<li>Avocat<\/li>\n<li>Chou<\/li>\n<li>Aubergine<\/li>\n<li>Kiwi<\/li>\n<li>Mangue<\/li>\n<li>Oignons<\/li>\n<li>Papaye<\/li>\n<li>Ananas<\/li>\n<li>Pamplemousse<\/li>\n<li>Chou-fleur<\/li>\n<li>Le ma\u00efs doux<\/li>\n<li>Petits pois<\/li>\n<li>Patates douces<\/li>\n<\/ul>\n<p>Une fa\u00e7on de plus de faire des courses bonnes pour la sant\u00e9 sans vous ruiner !<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je reviens aujourd\u2019hui avec un nouvel article sur le Bio. Les produits biologiques ont fait une entr\u00e9e fracassante dans nos rayons depuis un moment maintenant, et vous \u00eates de plus en plus nombreux et nombreuses \u00e0 les consommer . Personnellement je ne suis pas une militante du bio, cependant je privil\u00e9gie le bio sur certains aliments. Les aliments biologiques divisent les opinions, souvent plus chers sont ils vraiment d\u00e9pourvus de pesticides ? Je pense que oui en tout cas en partie, mais il faut savoir que si nous faisons une comparaison nutritionnelle l&rsquo;alimentation biologique et \u00a0\u00bb classiques\u00a0\u00bb la diff\u00e9rence n&rsquo;est pas tr\u00e8s significative en moyenne . \u00a0 Certains aliments, cependant quand ils sont cultiv\u00e9s de mani\u00e8re conventionnelle, exige un niveaux de pesticide assez important : Pommes Poivrons C\u00e9leri Cerises Raisins Chou fris\u00e9 \u00c9pinard Nectarines P\u00eaches Fraises Concombres Tomates cerise Pois gourmand Pommes de terre Si vous voulez faire attention \u00e0 la quantit\u00e9 de pesticide ces aliments sont \u00e0 acheter de pr\u00e9f\u00e9rence bio, ainsi que le lait et les oeufs qui viennent directement des animaux . Si vous voulez faire quelques \u00e9conomie certains aliments ne sont cultiv\u00e9 qu&rsquo;avec tr\u00e8s peu de pesticides : Asperges Avocat Chou Aubergine Kiwi Mangue Oignons Papaye Ananas Pamplemousse Chou-fleur Le ma\u00efs doux Petits pois Patates douces Une fa\u00e7on de plus de faire des courses bonnes pour la sant\u00e9 sans vous ruiner ! &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":558,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"footnotes":""},"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les aliments \u00e0 consommer Bio - Di\u00e8t et Forme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dietetforme.fr\/blog\/les-aliments-a-consommer-bio\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les aliments \u00e0 consommer Bio - Di\u00e8t et Forme\" \/>\n<meta property=\"og:description\" content=\"Je reviens aujourd\u2019hui avec un nouvel article sur le Bio. Les produits biologiques ont fait une entr\u00e9e fracassante dans nos rayons depuis un moment maintenant, et vous \u00eates de plus en plus nombreux et nombreuses \u00e0 les consommer . Personnellement je ne suis pas une militante du bio, cependant je privil\u00e9gie le bio sur certains aliments. Les aliments biologiques divisent les opinions, souvent plus chers sont ils vraiment d\u00e9pourvus de pesticides ? Je pense que oui en tout cas en partie, mais il faut savoir que si nous faisons une comparaison nutritionnelle l&rsquo;alimentation biologique et \u00a0\u00bb classiques\u00a0\u00bb la diff\u00e9rence n&rsquo;est pas tr\u00e8s significative en moyenne . \u00a0 Certains aliments, cependant quand ils sont cultiv\u00e9s de mani\u00e8re conventionnelle, exige un niveaux de pesticide assez important : Pommes Poivrons C\u00e9leri Cerises Raisins Chou fris\u00e9 \u00c9pinard Nectarines P\u00eaches Fraises Concombres Tomates cerise Pois gourmand Pommes de terre Si vous voulez faire attention \u00e0 la quantit\u00e9 de pesticide ces aliments sont \u00e0 acheter de pr\u00e9f\u00e9rence bio, ainsi que le lait et les oeufs qui viennent directement des animaux . Si vous voulez faire quelques \u00e9conomie certains aliments ne sont cultiv\u00e9 qu&rsquo;avec tr\u00e8s peu de pesticides : Asperges Avocat Chou Aubergine Kiwi Mangue Oignons Papaye Ananas Pamplemousse Chou-fleur Le ma\u00efs doux Petits pois Patates douces Une fa\u00e7on de plus de faire des courses bonnes pour la sant\u00e9 sans vous ruiner ! &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dietetforme.fr\/blog\/les-aliments-a-consommer-bio\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e8t et Forme\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lddietetforme\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-02T09:16:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-19T13:32:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dietetforme.fr\/blog\/wp-content\/uploads\/2016\/09\/gooseberry-1556683_640-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"344\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"L\u00e9onore Duchez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"L\u00e9onore Duchez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/les-aliments-a-consommer-bio\/\",\"url\":\"https:\/\/dietetforme.fr\/blog\/les-aliments-a-consommer-bio\/\",\"name\":\"Les aliments \u00e0 consommer Bio - Di\u00e8t et Forme\",\"isPartOf\":{\"@id\":\"https:\/\/dietetforme.fr\/blog\/#website\"},\"datePublished\":\"2016-09-02T09:16:53+00:00\",\"dateModified\":\"2019-02-19T13:32:18+00:00\",\"author\":{\"@id\":\"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/dfda5751b55409cd7b4557f58765f7a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/dietetforme.fr\/blog\/les-aliments-a-consommer-bio\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dietetforme.fr\/blog\/les-aliments-a-consommer-bio\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/les-aliments-a-consommer-bio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dietetforme.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MES CONSEILS\",\"item\":\"https:\/\/dietetforme.fr\/blog\/cat\/trucs-astuces-conseils-nutrition-dietetiques\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les aliments \u00e0 consommer Bio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/#website\",\"url\":\"https:\/\/dietetforme.fr\/blog\/\",\"name\":\"Di\u00e8t et Forme\",\"description\":\"Blog de recettes et astuces di\u00e9t\u00e9tiques\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dietetforme.fr\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/dfda5751b55409cd7b4557f58765f7a2\",\"name\":\"L\u00e9onore Duchez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bcb12a51f6392d50f0d406d3f084b785?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bcb12a51f6392d50f0d406d3f084b785?s=96&d=mm&r=g\",\"caption\":\"L\u00e9onore Duchez\"},\"url\":\"https:\/\/dietetforme.fr\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les aliments \u00e0 consommer Bio - Di\u00e8t et Forme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dietetforme.fr\/blog\/les-aliments-a-consommer-bio\/","og_locale":"fr_FR","og_type":"article","og_title":"Les aliments \u00e0 consommer Bio - Di\u00e8t et Forme","og_description":"Je reviens aujourd\u2019hui avec un nouvel article sur le Bio. Les produits biologiques ont fait une entr\u00e9e fracassante dans nos rayons depuis un moment maintenant, et vous \u00eates de plus en plus nombreux et nombreuses \u00e0 les consommer . Personnellement je ne suis pas une militante du bio, cependant je privil\u00e9gie le bio sur certains aliments. Les aliments biologiques divisent les opinions, souvent plus chers sont ils vraiment d\u00e9pourvus de pesticides ? Je pense que oui en tout cas en partie, mais il faut savoir que si nous faisons une comparaison nutritionnelle l&rsquo;alimentation biologique et \u00a0\u00bb classiques\u00a0\u00bb la diff\u00e9rence n&rsquo;est pas tr\u00e8s significative en moyenne . \u00a0 Certains aliments, cependant quand ils sont cultiv\u00e9s de mani\u00e8re conventionnelle, exige un niveaux de pesticide assez important : Pommes Poivrons C\u00e9leri Cerises Raisins Chou fris\u00e9 \u00c9pinard Nectarines P\u00eaches Fraises Concombres Tomates cerise Pois gourmand Pommes de terre Si vous voulez faire attention \u00e0 la quantit\u00e9 de pesticide ces aliments sont \u00e0 acheter de pr\u00e9f\u00e9rence bio, ainsi que le lait et les oeufs qui viennent directement des animaux . Si vous voulez faire quelques \u00e9conomie certains aliments ne sont cultiv\u00e9 qu&rsquo;avec tr\u00e8s peu de pesticides : Asperges Avocat Chou Aubergine Kiwi Mangue Oignons Papaye Ananas Pamplemousse Chou-fleur Le ma\u00efs doux Petits pois Patates douces Une fa\u00e7on de plus de faire des courses bonnes pour la sant\u00e9 sans vous ruiner ! &nbsp;","og_url":"https:\/\/dietetforme.fr\/blog\/les-aliments-a-consommer-bio\/","og_site_name":"Di\u00e8t et Forme","article_publisher":"https:\/\/www.facebook.com\/lddietetforme\/","article_published_time":"2016-09-02T09:16:53+00:00","article_modified_time":"2019-02-19T13:32:18+00:00","og_image":[{"width":640,"height":344,"url":"https:\/\/dietetforme.fr\/blog\/wp-content\/uploads\/2016\/09\/gooseberry-1556683_640-2.jpg","type":"image\/jpeg"}],"author":"L\u00e9onore Duchez","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"L\u00e9onore Duchez","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dietetforme.fr\/blog\/les-aliments-a-consommer-bio\/","url":"https:\/\/dietetforme.fr\/blog\/les-aliments-a-consommer-bio\/","name":"Les aliments \u00e0 consommer Bio - Di\u00e8t et Forme","isPartOf":{"@id":"https:\/\/dietetforme.fr\/blog\/#website"},"datePublished":"2016-09-02T09:16:53+00:00","dateModified":"2019-02-19T13:32:18+00:00","author":{"@id":"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/dfda5751b55409cd7b4557f58765f7a2"},"breadcrumb":{"@id":"https:\/\/dietetforme.fr\/blog\/les-aliments-a-consommer-bio\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dietetforme.fr\/blog\/les-aliments-a-consommer-bio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dietetforme.fr\/blog\/les-aliments-a-consommer-bio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dietetforme.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"MES CONSEILS","item":"https:\/\/dietetforme.fr\/blog\/cat\/trucs-astuces-conseils-nutrition-dietetiques\/"},{"@type":"ListItem","position":3,"name":"Les aliments \u00e0 consommer Bio"}]},{"@type":"WebSite","@id":"https:\/\/dietetforme.fr\/blog\/#website","url":"https:\/\/dietetforme.fr\/blog\/","name":"Di\u00e8t et Forme","description":"Blog de recettes et astuces di\u00e9t\u00e9tiques","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dietetforme.fr\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/dfda5751b55409cd7b4557f58765f7a2","name":"L\u00e9onore Duchez","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bcb12a51f6392d50f0d406d3f084b785?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bcb12a51f6392d50f0d406d3f084b785?s=96&d=mm&r=g","caption":"L\u00e9onore Duchez"},"url":"https:\/\/dietetforme.fr\/blog\/author\/admin\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/posts\/557"}],"collection":[{"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/comments?post=557"}],"version-history":[{"count":1,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/posts\/557\/revisions"}],"predecessor-version":[{"id":559,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/posts\/557\/revisions\/559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/media\/558"}],"wp:attachment":[{"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/media?parent=557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/categories?post=557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/tags?post=557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}