{"id":1583,"date":"2019-05-27T08:28:13","date_gmt":"2019-05-27T08:28:13","guid":{"rendered":"https:\/\/dietetforme.fr\/blog\/?p=1583"},"modified":"2019-05-27T08:28:16","modified_gmt":"2019-05-27T08:28:16","slug":"quiche-brocoli-truite-fumee-crevette","status":"publish","type":"post","link":"https:\/\/dietetforme.fr\/blog\/quiche-brocoli-truite-fumee-crevette\/","title":{"rendered":"Quiche brocoli truite fum\u00e9e crevette"},"content":{"rendered":"\n<p>Les beaux jours arrivent, les d\u00eeners se font plus longs et conviviaux. Une recette originale de quiche \u00e0 base de Brocolis qui mettra tout le monde d\u2019accord : <\/p>\n\n\n\n<p>Ingr\u00e9dient pour 1 tarte&nbsp;: <\/p>\n\n\n\n<ul><li>200g de truite fum\u00e9e <\/li><li>200g de crevettes cuites d\u00e9cortiqu\u00e9es <\/li><li>200g de brocolis <\/li><li>1 p\u00e2te bris\u00e9e <\/li><li>10 cl de cr\u00e8me liquide <\/li><li>4 \u0153ufs <\/li><li>Sel, poivre <\/li><\/ul>\n\n\n\n<p>Dans un premier temps pr\u00e9chauffer votre four \u00e0 180\u00b0<\/p>\n\n\n\n<p>Porter \u00e0 \u00e9bullition une casserole d\u2019eau, faites cuire 7 \u00e0 10\nminutes votre brocoli, d\u00e9taill\u00e9 en petits morceaux. <\/p>\n\n\n\n<p>Dans un saladier m\u00e9langer les \u0153ufs, et la cr\u00e8me. <\/p>\n\n\n\n<p>Ajouter la truite en petits morceaux et les crevettes <\/p>\n\n\n\n<p>Verser sur votre p\u00e2te la pr\u00e9paration, puis ajouter les\nbrocolis <\/p>\n\n\n\n<p>Enfourner 30 minutes \u00e0 180\u00b0<\/p>\n\n\n\n<p>D\u00e9guster ti\u00e8de ou froide avec une bonne m\u00e2che et une vinaigrette maison\u00a0! <\/p>\n\n\n\n<p>Bon app\u00e9tit ! <\/p>\n\n\n\n<p>Retrouver la version \u00e9pinard : <a href=\"https:\/\/www.marieclaire.fr\/cuisine\/quiche-ricotta-crevettes-et-brocoli,1202710.asp\">https:\/\/www.marieclaire.fr\/cuisine\/quiche-ricotta-crevettes-et-brocoli,1202710.asp<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les beaux jours arrivent, les d\u00eeners se font plus longs et conviviaux. Une recette originale de quiche \u00e0 base de Brocolis qui mettra tout le monde d\u2019accord : Ingr\u00e9dient pour 1 tarte&nbsp;: 200g de truite fum\u00e9e 200g de crevettes cuites d\u00e9cortiqu\u00e9es 200g de brocolis 1 p\u00e2te bris\u00e9e 10 cl de cr\u00e8me liquide 4 \u0153ufs Sel, poivre Dans un premier temps pr\u00e9chauffer votre four \u00e0 180\u00b0 Porter \u00e0 \u00e9bullition une casserole d\u2019eau, faites cuire 7 \u00e0 10 minutes votre brocoli, d\u00e9taill\u00e9 en petits morceaux. Dans un saladier m\u00e9langer les \u0153ufs, et la cr\u00e8me. Ajouter la truite en petits morceaux et les crevettes Verser sur votre p\u00e2te la pr\u00e9paration, puis ajouter les brocolis Enfourner 30 minutes \u00e0 180\u00b0 D\u00e9guster ti\u00e8de ou froide avec une bonne m\u00e2che et une vinaigrette maison\u00a0! Bon app\u00e9tit ! Retrouver la version \u00e9pinard : https:\/\/www.marieclaire.fr\/cuisine\/quiche-ricotta-crevettes-et-brocoli,1202710.asp<\/p>\n","protected":false},"author":1,"featured_media":1584,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"footnotes":""},"categories":[5],"tags":[24,182,170,9],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quiche brocoli truite fum\u00e9e crevette - Di\u00e8t et Forme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dietetforme.fr\/blog\/quiche-brocoli-truite-fumee-crevette\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quiche brocoli truite fum\u00e9e crevette - Di\u00e8t et Forme\" \/>\n<meta property=\"og:description\" content=\"Les beaux jours arrivent, les d\u00eeners se font plus longs et conviviaux. Une recette originale de quiche \u00e0 base de Brocolis qui mettra tout le monde d\u2019accord : Ingr\u00e9dient pour 1 tarte&nbsp;: 200g de truite fum\u00e9e 200g de crevettes cuites d\u00e9cortiqu\u00e9es 200g de brocolis 1 p\u00e2te bris\u00e9e 10 cl de cr\u00e8me liquide 4 \u0153ufs Sel, poivre Dans un premier temps pr\u00e9chauffer votre four \u00e0 180\u00b0 Porter \u00e0 \u00e9bullition une casserole d\u2019eau, faites cuire 7 \u00e0 10 minutes votre brocoli, d\u00e9taill\u00e9 en petits morceaux. Dans un saladier m\u00e9langer les \u0153ufs, et la cr\u00e8me. Ajouter la truite en petits morceaux et les crevettes Verser sur votre p\u00e2te la pr\u00e9paration, puis ajouter les brocolis Enfourner 30 minutes \u00e0 180\u00b0 D\u00e9guster ti\u00e8de ou froide avec une bonne m\u00e2che et une vinaigrette maison\u00a0! Bon app\u00e9tit ! Retrouver la version \u00e9pinard : https:\/\/www.marieclaire.fr\/cuisine\/quiche-ricotta-crevettes-et-brocoli,1202710.asp\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dietetforme.fr\/blog\/quiche-brocoli-truite-fumee-crevette\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e8t et Forme\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lddietetforme\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-27T08:28:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-27T08:28:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dietetforme.fr\/blog\/wp-content\/uploads\/2019\/05\/43365870.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"L\u00e9onore Duchez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"L\u00e9onore Duchez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/quiche-brocoli-truite-fumee-crevette\/\",\"url\":\"https:\/\/dietetforme.fr\/blog\/quiche-brocoli-truite-fumee-crevette\/\",\"name\":\"Quiche brocoli truite fum\u00e9e crevette - Di\u00e8t et Forme\",\"isPartOf\":{\"@id\":\"https:\/\/dietetforme.fr\/blog\/#website\"},\"datePublished\":\"2019-05-27T08:28:13+00:00\",\"dateModified\":\"2019-05-27T08:28:16+00:00\",\"author\":{\"@id\":\"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/dfda5751b55409cd7b4557f58765f7a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/dietetforme.fr\/blog\/quiche-brocoli-truite-fumee-crevette\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dietetforme.fr\/blog\/quiche-brocoli-truite-fumee-crevette\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/quiche-brocoli-truite-fumee-crevette\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dietetforme.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RECETTES\",\"item\":\"https:\/\/dietetforme.fr\/blog\/cat\/recettes-et-astuces-nutrition\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quiche brocoli truite fum\u00e9e crevette\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/#website\",\"url\":\"https:\/\/dietetforme.fr\/blog\/\",\"name\":\"Di\u00e8t et Forme\",\"description\":\"Blog de recettes et astuces di\u00e9t\u00e9tiques\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dietetforme.fr\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/dfda5751b55409cd7b4557f58765f7a2\",\"name\":\"L\u00e9onore Duchez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bcb12a51f6392d50f0d406d3f084b785?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bcb12a51f6392d50f0d406d3f084b785?s=96&d=mm&r=g\",\"caption\":\"L\u00e9onore Duchez\"},\"url\":\"https:\/\/dietetforme.fr\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quiche brocoli truite fum\u00e9e crevette - Di\u00e8t et Forme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dietetforme.fr\/blog\/quiche-brocoli-truite-fumee-crevette\/","og_locale":"fr_FR","og_type":"article","og_title":"Quiche brocoli truite fum\u00e9e crevette - Di\u00e8t et Forme","og_description":"Les beaux jours arrivent, les d\u00eeners se font plus longs et conviviaux. Une recette originale de quiche \u00e0 base de Brocolis qui mettra tout le monde d\u2019accord : Ingr\u00e9dient pour 1 tarte&nbsp;: 200g de truite fum\u00e9e 200g de crevettes cuites d\u00e9cortiqu\u00e9es 200g de brocolis 1 p\u00e2te bris\u00e9e 10 cl de cr\u00e8me liquide 4 \u0153ufs Sel, poivre Dans un premier temps pr\u00e9chauffer votre four \u00e0 180\u00b0 Porter \u00e0 \u00e9bullition une casserole d\u2019eau, faites cuire 7 \u00e0 10 minutes votre brocoli, d\u00e9taill\u00e9 en petits morceaux. Dans un saladier m\u00e9langer les \u0153ufs, et la cr\u00e8me. Ajouter la truite en petits morceaux et les crevettes Verser sur votre p\u00e2te la pr\u00e9paration, puis ajouter les brocolis Enfourner 30 minutes \u00e0 180\u00b0 D\u00e9guster ti\u00e8de ou froide avec une bonne m\u00e2che et une vinaigrette maison\u00a0! Bon app\u00e9tit ! Retrouver la version \u00e9pinard : https:\/\/www.marieclaire.fr\/cuisine\/quiche-ricotta-crevettes-et-brocoli,1202710.asp","og_url":"https:\/\/dietetforme.fr\/blog\/quiche-brocoli-truite-fumee-crevette\/","og_site_name":"Di\u00e8t et Forme","article_publisher":"https:\/\/www.facebook.com\/lddietetforme\/","article_published_time":"2019-05-27T08:28:13+00:00","article_modified_time":"2019-05-27T08:28:16+00:00","og_image":[{"width":1000,"height":1500,"url":"https:\/\/dietetforme.fr\/blog\/wp-content\/uploads\/2019\/05\/43365870.jpg","type":"image\/jpeg"}],"author":"L\u00e9onore Duchez","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"L\u00e9onore Duchez","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dietetforme.fr\/blog\/quiche-brocoli-truite-fumee-crevette\/","url":"https:\/\/dietetforme.fr\/blog\/quiche-brocoli-truite-fumee-crevette\/","name":"Quiche brocoli truite fum\u00e9e crevette - Di\u00e8t et Forme","isPartOf":{"@id":"https:\/\/dietetforme.fr\/blog\/#website"},"datePublished":"2019-05-27T08:28:13+00:00","dateModified":"2019-05-27T08:28:16+00:00","author":{"@id":"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/dfda5751b55409cd7b4557f58765f7a2"},"breadcrumb":{"@id":"https:\/\/dietetforme.fr\/blog\/quiche-brocoli-truite-fumee-crevette\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dietetforme.fr\/blog\/quiche-brocoli-truite-fumee-crevette\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dietetforme.fr\/blog\/quiche-brocoli-truite-fumee-crevette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dietetforme.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"RECETTES","item":"https:\/\/dietetforme.fr\/blog\/cat\/recettes-et-astuces-nutrition\/"},{"@type":"ListItem","position":3,"name":"Quiche brocoli truite fum\u00e9e crevette"}]},{"@type":"WebSite","@id":"https:\/\/dietetforme.fr\/blog\/#website","url":"https:\/\/dietetforme.fr\/blog\/","name":"Di\u00e8t et Forme","description":"Blog de recettes et astuces di\u00e9t\u00e9tiques","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dietetforme.fr\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/dfda5751b55409cd7b4557f58765f7a2","name":"L\u00e9onore Duchez","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bcb12a51f6392d50f0d406d3f084b785?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bcb12a51f6392d50f0d406d3f084b785?s=96&d=mm&r=g","caption":"L\u00e9onore Duchez"},"url":"https:\/\/dietetforme.fr\/blog\/author\/admin\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/posts\/1583"}],"collection":[{"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/comments?post=1583"}],"version-history":[{"count":1,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/posts\/1583\/revisions"}],"predecessor-version":[{"id":1585,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/posts\/1583\/revisions\/1585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/media\/1584"}],"wp:attachment":[{"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/media?parent=1583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/categories?post=1583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/tags?post=1583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}