{"id":1041,"date":"2017-10-29T16:19:02","date_gmt":"2017-10-29T16:19:02","guid":{"rendered":"http:\/\/dietetforme.fr\/?p=1041"},"modified":"2019-02-19T13:29:19","modified_gmt":"2019-02-19T13:29:19","slug":"quitoque-met-fin-a-la-corvee-des-courses","status":"publish","type":"post","link":"https:\/\/dietetforme.fr\/blog\/quitoque-met-fin-a-la-corvee-des-courses\/","title":{"rendered":"QUITOQUE met fin \u00e0 la corv\u00e9e des courses !"},"content":{"rendered":"<p style=\"text-align: center;\">\n<strong>La corv\u00e9e des courses est d\u00e9sormais finie !<\/strong><\/p>\n<p><a href=\"http:\/\/dietetforme.fr\/wp-content\/uploads\/2017\/10\/QuiToque_accueil.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1044 aligncenter\" src=\"http:\/\/dietetforme.fr\/wp-content\/uploads\/2017\/10\/QuiToque_accueil-300x177.jpg\" alt=\"\" width=\"300\" height=\"177\" srcset=\"https:\/\/dietetforme.fr\/blog\/wp-content\/uploads\/2017\/10\/QuiToque_accueil-300x177.jpg 300w, https:\/\/dietetforme.fr\/blog\/wp-content\/uploads\/2017\/10\/QuiToque_accueil.jpg 535w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.quitoque.fr\/\">QUITOQUE<\/a>\u00a0est le site que vous devez conna\u00eetre pour vous faciliter la vie !<\/p>\n<p>Des paniers recettes qui facilitent votre quotidien, <em>livr\u00e9s \u00e0 votre domicile ou sur votre lieu de travail<\/em> !<\/p>\n<p>Dans ces paniers recettes vous trouverez :<br \/>\n&#8211; Des recettes imagin\u00e9es par une chef (C\u00e9line) cuistot, pour favoriser le fait maison et l\u2019\u00e9quilibre alimentaire<br \/>\n&#8211; Des produits frais et de saison pour les r\u00e9aliser<br \/>\n&#8211; Entre 3 et 5 recettes (selon votre choix) pr\u00eat entre 15 et 30 minutes<br \/>\n&#8211; Un calendrier de livraison modulable<br \/>\n&#8211; Des produits origine France privil\u00e9gi\u00e9e<\/p>\n<p><a href=\"http:\/\/dietetforme.fr\/wp-content\/uploads\/2017\/10\/thPUK5S53X.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1043 aligncenter\" src=\"http:\/\/dietetforme.fr\/wp-content\/uploads\/2017\/10\/thPUK5S53X-300x180.jpg\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/dietetforme.fr\/blog\/wp-content\/uploads\/2017\/10\/thPUK5S53X-300x180.jpg 300w, https:\/\/dietetforme.fr\/blog\/wp-content\/uploads\/2017\/10\/thPUK5S53X.jpg 322w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><strong>Non QUITOQUE n\u2019est pas un site qui vous promet de maigrir en un mois, ce n\u2019est pas leur philosophie est c\u2019est pour cette raison que je me permets d\u2019en parler sur mon site<\/strong>. Les recettes sont \u00e9labor\u00e9es par une di\u00e9t\u00e9ticienne<strong> et vous garantit l\u2019\u00e9quilibre alimentaire dont vous avez besoin, l\u2019\u00e9quilibre alimentaire que \u201cje prescris\u201c \u00e0 ma patient\u00e8le<\/strong>.<\/p>\n<p>Vous pouvez choisir le panier qui correspond le mieux \u00e0 votre foyer avec un panier COUPLE ou un panier FAMILLE, vous choisirez ensuite le nombre de repas (entre 3 et 4 pour le panier couple et 3 et 5 pour le panier famille). La livraison et gratuite et vous choisissez le jour et le lieu de celle-ci !<\/p>\n<p>Vous pouvez moduler votre panier :<br \/>\n&#8211; Panier sans porc<br \/>\n&#8211; Panier v\u00e9g\u00e9tarien<br \/>\n&#8211; Panier sans poisson<br \/>\n&#8211; Panier sans viande<br \/>\nDes paniers qui vous ressemble !<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/dietetforme.fr\/wp-content\/uploads\/2017\/10\/ob_85dea8_toque.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1042\" src=\"http:\/\/dietetforme.fr\/wp-content\/uploads\/2017\/10\/ob_85dea8_toque-300x88.png\" alt=\"\" width=\"433\" height=\"127\" srcset=\"https:\/\/dietetforme.fr\/blog\/wp-content\/uploads\/2017\/10\/ob_85dea8_toque-300x88.png 300w, https:\/\/dietetforme.fr\/blog\/wp-content\/uploads\/2017\/10\/ob_85dea8_toque-768x224.png 768w, https:\/\/dietetforme.fr\/blog\/wp-content\/uploads\/2017\/10\/ob_85dea8_toque-1024x299.png 1024w, https:\/\/dietetforme.fr\/blog\/wp-content\/uploads\/2017\/10\/ob_85dea8_toque.png 1117w\" sizes=\"(max-width: 433px) 100vw, 433px\" \/><\/a><\/p>\n<p>En option vous pouvez choisir un panier :<br \/>\n&#8211; De fruits frais<br \/>\n&#8211; De fromage<br \/>\n&#8211; De vin<br \/>\n&#8211; Vos desserts<br \/>\n&#8211; Vos petits d\u00e9jeuners<\/p>\n<p><strong>Ce site vous facilite vraiment vos journ\u00e9es vous perdrez moins de temps aux courses et le soir, vos recettes sont d\u00e9j\u00e0 \u00e9tablies, il ne vous reste plus qu\u2019\u00e0 cuisiner (un peu mais pas trop !) et vous mettre \u00e0 table !<\/strong><\/p>\n<p>D\u00e9couvrez d\u00e8s \u00e0 pr\u00e9sent les recettes des semaines \u00e0 venir et le concept sur :\u00a0<a href=\"https:\/\/www.quitoque.fr\/\">QUITOQUE.FR<\/a><\/p>\n<p>Gr\u00e2ce \u00e0 un code promo vous b\u00e9n\u00e9ficiez de 30 euros offerts sur l\u2019achat de votre premier panier QUITOQUE (pour un montant minimum de 57 euros), cette offre est sans engagement, alors pourquoi pas tester ?<\/p>\n<h1><strong>CODE PROMO : KAKI75-30<\/strong><\/h1>\n","protected":false},"excerpt":{"rendered":"<p>La corv\u00e9e des courses est d\u00e9sormais finie ! QUITOQUE\u00a0est le site que vous devez conna\u00eetre pour vous faciliter la vie ! Des paniers recettes qui facilitent votre quotidien, livr\u00e9s \u00e0 votre domicile ou sur votre lieu de travail ! Dans ces paniers recettes vous trouverez : &#8211; Des recettes imagin\u00e9es par une chef (C\u00e9line) cuistot, pour favoriser le fait maison et l\u2019\u00e9quilibre alimentaire &#8211; Des produits frais et de saison pour les r\u00e9aliser &#8211; Entre 3 et 5 recettes (selon votre choix) pr\u00eat entre 15 et 30 minutes &#8211; Un calendrier de livraison modulable &#8211; Des produits origine France privil\u00e9gi\u00e9e Non QUITOQUE n\u2019est pas un site qui vous promet de maigrir en un mois, ce n\u2019est pas leur philosophie est c\u2019est pour cette raison que je me permets d\u2019en parler sur mon site. Les recettes sont \u00e9labor\u00e9es par une di\u00e9t\u00e9ticienne et vous garantit l\u2019\u00e9quilibre alimentaire dont vous avez besoin, l\u2019\u00e9quilibre alimentaire que \u201cje prescris\u201c \u00e0 ma patient\u00e8le. Vous pouvez choisir le panier qui correspond le mieux \u00e0 votre foyer avec un panier COUPLE ou un panier FAMILLE, vous choisirez ensuite le nombre de repas (entre 3 et 4 pour le panier couple et 3 et 5 pour le panier famille). La livraison et gratuite et vous choisissez le jour et le lieu de celle-ci ! Vous pouvez moduler votre panier : &#8211; Panier sans porc &#8211; Panier v\u00e9g\u00e9tarien &#8211; Panier sans poisson &#8211; Panier sans viande Des paniers qui vous ressemble ! En option vous pouvez choisir un panier : &#8211; De fruits frais &#8211; De fromage &#8211; De vin &#8211; Vos desserts &#8211; Vos petits d\u00e9jeuners Ce site vous facilite vraiment vos journ\u00e9es vous perdrez moins de temps aux courses et le soir, vos recettes sont d\u00e9j\u00e0 \u00e9tablies, il ne vous reste plus qu\u2019\u00e0 cuisiner (un peu mais pas trop !) et vous mettre \u00e0 table ! D\u00e9couvrez d\u00e8s \u00e0 pr\u00e9sent les recettes des semaines \u00e0 venir et le concept sur :\u00a0QUITOQUE.FR Gr\u00e2ce \u00e0 un code promo vous b\u00e9n\u00e9ficiez de 30 euros offerts sur l\u2019achat de votre premier panier QUITOQUE (pour un montant minimum de 57 euros), cette offre est sans engagement, alors pourquoi pas tester ? CODE PROMO : KAKI75-30<\/p>\n","protected":false},"author":1,"featured_media":1045,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"footnotes":""},"categories":[4,3],"tags":[17,41,50,28,24,21,115,9,26],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>QUITOQUE met fin \u00e0 la corv\u00e9e des courses ! - Di\u00e8t et Forme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dietetforme.fr\/blog\/quitoque-met-fin-a-la-corvee-des-courses\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"QUITOQUE met fin \u00e0 la corv\u00e9e des courses ! - Di\u00e8t et Forme\" \/>\n<meta property=\"og:description\" content=\"La corv\u00e9e des courses est d\u00e9sormais finie ! QUITOQUE\u00a0est le site que vous devez conna\u00eetre pour vous faciliter la vie ! Des paniers recettes qui facilitent votre quotidien, livr\u00e9s \u00e0 votre domicile ou sur votre lieu de travail ! Dans ces paniers recettes vous trouverez : &#8211; Des recettes imagin\u00e9es par une chef (C\u00e9line) cuistot, pour favoriser le fait maison et l\u2019\u00e9quilibre alimentaire &#8211; Des produits frais et de saison pour les r\u00e9aliser &#8211; Entre 3 et 5 recettes (selon votre choix) pr\u00eat entre 15 et 30 minutes &#8211; Un calendrier de livraison modulable &#8211; Des produits origine France privil\u00e9gi\u00e9e Non QUITOQUE n\u2019est pas un site qui vous promet de maigrir en un mois, ce n\u2019est pas leur philosophie est c\u2019est pour cette raison que je me permets d\u2019en parler sur mon site. Les recettes sont \u00e9labor\u00e9es par une di\u00e9t\u00e9ticienne et vous garantit l\u2019\u00e9quilibre alimentaire dont vous avez besoin, l\u2019\u00e9quilibre alimentaire que \u201cje prescris\u201c \u00e0 ma patient\u00e8le. Vous pouvez choisir le panier qui correspond le mieux \u00e0 votre foyer avec un panier COUPLE ou un panier FAMILLE, vous choisirez ensuite le nombre de repas (entre 3 et 4 pour le panier couple et 3 et 5 pour le panier famille). La livraison et gratuite et vous choisissez le jour et le lieu de celle-ci ! Vous pouvez moduler votre panier : &#8211; Panier sans porc &#8211; Panier v\u00e9g\u00e9tarien &#8211; Panier sans poisson &#8211; Panier sans viande Des paniers qui vous ressemble ! En option vous pouvez choisir un panier : &#8211; De fruits frais &#8211; De fromage &#8211; De vin &#8211; Vos desserts &#8211; Vos petits d\u00e9jeuners Ce site vous facilite vraiment vos journ\u00e9es vous perdrez moins de temps aux courses et le soir, vos recettes sont d\u00e9j\u00e0 \u00e9tablies, il ne vous reste plus qu\u2019\u00e0 cuisiner (un peu mais pas trop !) et vous mettre \u00e0 table ! D\u00e9couvrez d\u00e8s \u00e0 pr\u00e9sent les recettes des semaines \u00e0 venir et le concept sur :\u00a0QUITOQUE.FR Gr\u00e2ce \u00e0 un code promo vous b\u00e9n\u00e9ficiez de 30 euros offerts sur l\u2019achat de votre premier panier QUITOQUE (pour un montant minimum de 57 euros), cette offre est sans engagement, alors pourquoi pas tester ? CODE PROMO : KAKI75-30\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dietetforme.fr\/blog\/quitoque-met-fin-a-la-corvee-des-courses\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e8t et Forme\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lddietetforme\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-29T16:19:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-19T13:29:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dietetforme.fr\/blog\/wp-content\/uploads\/2017\/10\/quitoque.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"930\" \/>\n\t<meta property=\"og:image:height\" content=\"618\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"L\u00e9onore Duchez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"L\u00e9onore Duchez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/quitoque-met-fin-a-la-corvee-des-courses\/\",\"url\":\"https:\/\/dietetforme.fr\/blog\/quitoque-met-fin-a-la-corvee-des-courses\/\",\"name\":\"QUITOQUE met fin \u00e0 la corv\u00e9e des courses ! - Di\u00e8t et Forme\",\"isPartOf\":{\"@id\":\"https:\/\/dietetforme.fr\/blog\/#website\"},\"datePublished\":\"2017-10-29T16:19:02+00:00\",\"dateModified\":\"2019-02-19T13:29:19+00:00\",\"author\":{\"@id\":\"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/dfda5751b55409cd7b4557f58765f7a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/dietetforme.fr\/blog\/quitoque-met-fin-a-la-corvee-des-courses\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dietetforme.fr\/blog\/quitoque-met-fin-a-la-corvee-des-courses\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/quitoque-met-fin-a-la-corvee-des-courses\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dietetforme.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MES CONSEILS\",\"item\":\"https:\/\/dietetforme.fr\/blog\/cat\/trucs-astuces-conseils-nutrition-dietetiques\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"QUITOQUE met fin \u00e0 la corv\u00e9e des courses !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/#website\",\"url\":\"https:\/\/dietetforme.fr\/blog\/\",\"name\":\"Di\u00e8t et Forme\",\"description\":\"Blog de recettes et astuces di\u00e9t\u00e9tiques\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dietetforme.fr\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/dfda5751b55409cd7b4557f58765f7a2\",\"name\":\"L\u00e9onore Duchez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bcb12a51f6392d50f0d406d3f084b785?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bcb12a51f6392d50f0d406d3f084b785?s=96&d=mm&r=g\",\"caption\":\"L\u00e9onore Duchez\"},\"url\":\"https:\/\/dietetforme.fr\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"QUITOQUE met fin \u00e0 la corv\u00e9e des courses ! - Di\u00e8t et Forme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dietetforme.fr\/blog\/quitoque-met-fin-a-la-corvee-des-courses\/","og_locale":"fr_FR","og_type":"article","og_title":"QUITOQUE met fin \u00e0 la corv\u00e9e des courses ! - Di\u00e8t et Forme","og_description":"La corv\u00e9e des courses est d\u00e9sormais finie ! QUITOQUE\u00a0est le site que vous devez conna\u00eetre pour vous faciliter la vie ! Des paniers recettes qui facilitent votre quotidien, livr\u00e9s \u00e0 votre domicile ou sur votre lieu de travail ! Dans ces paniers recettes vous trouverez : &#8211; Des recettes imagin\u00e9es par une chef (C\u00e9line) cuistot, pour favoriser le fait maison et l\u2019\u00e9quilibre alimentaire &#8211; Des produits frais et de saison pour les r\u00e9aliser &#8211; Entre 3 et 5 recettes (selon votre choix) pr\u00eat entre 15 et 30 minutes &#8211; Un calendrier de livraison modulable &#8211; Des produits origine France privil\u00e9gi\u00e9e Non QUITOQUE n\u2019est pas un site qui vous promet de maigrir en un mois, ce n\u2019est pas leur philosophie est c\u2019est pour cette raison que je me permets d\u2019en parler sur mon site. Les recettes sont \u00e9labor\u00e9es par une di\u00e9t\u00e9ticienne et vous garantit l\u2019\u00e9quilibre alimentaire dont vous avez besoin, l\u2019\u00e9quilibre alimentaire que \u201cje prescris\u201c \u00e0 ma patient\u00e8le. Vous pouvez choisir le panier qui correspond le mieux \u00e0 votre foyer avec un panier COUPLE ou un panier FAMILLE, vous choisirez ensuite le nombre de repas (entre 3 et 4 pour le panier couple et 3 et 5 pour le panier famille). La livraison et gratuite et vous choisissez le jour et le lieu de celle-ci ! Vous pouvez moduler votre panier : &#8211; Panier sans porc &#8211; Panier v\u00e9g\u00e9tarien &#8211; Panier sans poisson &#8211; Panier sans viande Des paniers qui vous ressemble ! En option vous pouvez choisir un panier : &#8211; De fruits frais &#8211; De fromage &#8211; De vin &#8211; Vos desserts &#8211; Vos petits d\u00e9jeuners Ce site vous facilite vraiment vos journ\u00e9es vous perdrez moins de temps aux courses et le soir, vos recettes sont d\u00e9j\u00e0 \u00e9tablies, il ne vous reste plus qu\u2019\u00e0 cuisiner (un peu mais pas trop !) et vous mettre \u00e0 table ! D\u00e9couvrez d\u00e8s \u00e0 pr\u00e9sent les recettes des semaines \u00e0 venir et le concept sur :\u00a0QUITOQUE.FR Gr\u00e2ce \u00e0 un code promo vous b\u00e9n\u00e9ficiez de 30 euros offerts sur l\u2019achat de votre premier panier QUITOQUE (pour un montant minimum de 57 euros), cette offre est sans engagement, alors pourquoi pas tester ? CODE PROMO : KAKI75-30","og_url":"https:\/\/dietetforme.fr\/blog\/quitoque-met-fin-a-la-corvee-des-courses\/","og_site_name":"Di\u00e8t et Forme","article_publisher":"https:\/\/www.facebook.com\/lddietetforme\/","article_published_time":"2017-10-29T16:19:02+00:00","article_modified_time":"2019-02-19T13:29:19+00:00","og_image":[{"width":930,"height":618,"url":"https:\/\/dietetforme.fr\/blog\/wp-content\/uploads\/2017\/10\/quitoque.jpg","type":"image\/jpeg"}],"author":"L\u00e9onore Duchez","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"L\u00e9onore Duchez","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dietetforme.fr\/blog\/quitoque-met-fin-a-la-corvee-des-courses\/","url":"https:\/\/dietetforme.fr\/blog\/quitoque-met-fin-a-la-corvee-des-courses\/","name":"QUITOQUE met fin \u00e0 la corv\u00e9e des courses ! - Di\u00e8t et Forme","isPartOf":{"@id":"https:\/\/dietetforme.fr\/blog\/#website"},"datePublished":"2017-10-29T16:19:02+00:00","dateModified":"2019-02-19T13:29:19+00:00","author":{"@id":"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/dfda5751b55409cd7b4557f58765f7a2"},"breadcrumb":{"@id":"https:\/\/dietetforme.fr\/blog\/quitoque-met-fin-a-la-corvee-des-courses\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dietetforme.fr\/blog\/quitoque-met-fin-a-la-corvee-des-courses\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dietetforme.fr\/blog\/quitoque-met-fin-a-la-corvee-des-courses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dietetforme.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"MES CONSEILS","item":"https:\/\/dietetforme.fr\/blog\/cat\/trucs-astuces-conseils-nutrition-dietetiques\/"},{"@type":"ListItem","position":3,"name":"QUITOQUE met fin \u00e0 la corv\u00e9e des courses !"}]},{"@type":"WebSite","@id":"https:\/\/dietetforme.fr\/blog\/#website","url":"https:\/\/dietetforme.fr\/blog\/","name":"Di\u00e8t et Forme","description":"Blog de recettes et astuces di\u00e9t\u00e9tiques","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dietetforme.fr\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/dfda5751b55409cd7b4557f58765f7a2","name":"L\u00e9onore Duchez","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dietetforme.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bcb12a51f6392d50f0d406d3f084b785?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bcb12a51f6392d50f0d406d3f084b785?s=96&d=mm&r=g","caption":"L\u00e9onore Duchez"},"url":"https:\/\/dietetforme.fr\/blog\/author\/admin\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/posts\/1041"}],"collection":[{"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/comments?post=1041"}],"version-history":[{"count":2,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/posts\/1041\/revisions"}],"predecessor-version":[{"id":1047,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/posts\/1041\/revisions\/1047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/media\/1045"}],"wp:attachment":[{"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/media?parent=1041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/categories?post=1041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dietetforme.fr\/blog\/wp-json\/wp\/v2\/tags?post=1041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}